{"id":1,"count":35,"description":"Le Club Helv\u00e9tique publie des positions sur des discussions en cours, ou pour susciter des explications n\u00e9cessaires sur des questions importantes de notre temps. Il lance \u00e9galement des appels sur des \u00e9v\u00e8nements particuliers, pr\u00e9sents ou pass\u00e9s, de la vie politique ou sociale.","link":"https:\/\/clubhelvetique.ch\/fr\/category\/stellungnahmen\/","name":"Positions et appels","slug":"stellungnahmen","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/clubhelvetique.ch\/fr\/wp-json\/wp\/v2\/categories\/1"}],"collection":[{"href":"https:\/\/clubhelvetique.ch\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/clubhelvetique.ch\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/clubhelvetique.ch\/fr\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}